{"id":16132,"date":"2020-09-14T12:07:05","date_gmt":"2020-09-14T10:07:05","guid":{"rendered":"https:\/\/speakingo.com\/?p=16132"},"modified":"2021-11-07T15:55:13","modified_gmt":"2021-11-07T14:55:13","slug":"pronombres-posesivos-possessive-pronouns","status":"publish","type":"post","link":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/","title":{"rendered":"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns)"},"content":{"rendered":"<p>\u00bfPor qu\u00e9 decimos a veces <em>my<\/em> y veces <em>mine<\/em> como la gaviota de Nemo? Porque a veces tenemos que usar el adjetivo posesivo popular y a veces el pronombre posesivo ingl\u00e9s.<\/p>\n<p><!--more--><\/p>\n<hr \/>\n<div><\/div>\n<h2>Posesivo est\u00e1 bien, pero pronombre o adjetivo, \u00a1esa es la cuesti\u00f3n!<\/h2>\n<p>A veces puedes encontrar un poco una forma po\u00e9tica <em>mine<\/em>, a veces escucharemos el popular <em>my<\/em>. Traduciremos estas dos palabras al polaco como el m\u00edo&#8230;<\/p>\n<p>Desafortunadamente, esta es otra \u00e1rea de la gram\u00e1tica inglesa que no coincide con la gram\u00e1tica polaca. Por lo tanto, antes de discutir qu\u00e9 son los pronombres posesivos <em>(possessive pronouns)<\/em>, debemos recordar qu\u00e9 son los adjetivos posesivos <em>(possessive adjectives)<\/em>.<\/p>\n<h2><em>\u00bfQu\u00e9 son los adjetivos posesivos(possessive adjectives)?<\/em><\/h2>\n<p>Los adjetivos posesivos <em>(possessive adjectives) <\/em>muestran que algo le pertenece a alguien, que alguien lo \u00abtiene\u00bb. Sin entrar en mayor filosof\u00eda, estas son palabras como:<\/p>\n<ul>\n<li>mi\u2013 <em>my<\/em><\/li>\n<li>tu\u2013 <em>your\u00a0<\/em><\/li>\n<li>su\u2013 <em>her\u00a0<\/em><\/li>\n<li>su- <em>his\u00a0<\/em><\/li>\n<li>su\u2013 <em>its <\/em>(sin <a href=\"https:\/\/speakingo.com\/es\/apostrofe-ingles\/\">apostr\u00f3fo<\/a>!)<\/li>\n<\/ul>\n<p>y en plural<\/p>\n<ul>\n<li>nuestro \u2013 <em>our<\/em><\/li>\n<li>vuestro \u2013 <em>your<\/em><\/li>\n<li>su \u2013 <em>their<\/em><\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-9870 size-full\" src=\"https:\/\/speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-adjectives-love.jpg\" alt=\"zaimki dzier\u017cawcze possessive adjectives\" width=\"640\" height=\"480\" \/><\/p>\n<h2><\/h2>\n<h2>Entonces, \u00bfqu\u00e9 son los pronombres posesivos <em>(possessive pronouns)?<\/em><\/h2>\n<p>Los pronombres posesivos <em>(possessive pronouns) <\/em>tambi\u00e9n muestran que alguien \u00absostiene\u00bb algo. Adem\u00e1s, a menudo se traducen al polaco de la misma manera que los adjetivos posesivos &#8230;<\/p>\n<p>Veamos estas dos oraciones:<\/p>\n<ul>\n<li>\u00a0<em>This is my fish.<\/em> (Este es mi pez. &#8211; adjetivo posesivo)<\/li>\n<li>\u00a0<em>This fish is mine.<\/em> (Este pez es m\u00edo &#8211; pronombre posesivo)<\/li>\n<\/ul>\n<p>En castellano es igual: mi &#8211; m\u00edo. Son dos palabras diferentes ya que son dos categor\u00edas gramaticales separadas.<\/p>\n<h3>\u00bfCu\u00e1les son los pronombres posesivos en ingl\u00e9s?<\/h3>\n<p>Excepto el <em>mine<\/em> y el <em>his<\/em>, parecen adjetivos posesivos con un pegajoso (sin <a href=\"https:\/\/speakingo.com\/es\/apostrofe-ingles\/\">apostr\u00f3fo<\/a>) -s al final.<\/p>\n<ul>\n<li><strong><em>mine<\/em><\/strong><\/li>\n<li><strong><em>yours<\/em><\/strong><\/li>\n<li><strong><em>his<\/em><\/strong><\/li>\n<li><strong><em>hers<\/em><\/strong><\/li>\n<li><strong><em>its<\/em><\/strong> m\u00e1s bien, evitamos<\/li>\n<\/ul>\n<p>y en plural<\/p>\n<ul>\n<li><strong><em>ours <\/em><\/strong><\/li>\n<li><strong><em>yours<\/em><\/strong><\/li>\n<li><strong><em>theirs<\/em><\/strong><\/li>\n<\/ul>\n<p>Tenga en cuenta que <em>his<\/em> se ve igual que el pronombre y el adjetivo posesivo. Tal simplificaci\u00f3n &#8230;<\/p>\n<figure id=\"attachment_7355\" aria-describedby=\"caption-attachment-7355\" style=\"width: 640px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-7355 size-full\" src=\"https:\/\/speakingo.com\/wp-content\/uploads\/2019\/01\/dopelniacz-saksonski-possessive-s.jpg\" alt=\"dope\u0142niacz sakso\u0144ski, possessive 's, genitive, gramatyka angielska\" width=\"640\" height=\"480\" \/><figcaption id=\"caption-attachment-7355\" class=\"wp-caption-text\"><em>Lee tambi\u00e9n: <a href=\"https:\/\/speakingo.com\/es\/ingles-sajon-genitivo-posesivo-s\/\">\u00bfPor qu\u00e9 el genitivo ingl\u00e9s es saj\u00f3n (possessive -s)?<\/a><\/em><\/figcaption><\/figure>\n<h3>\u00bfC\u00f3mo distinguir un adjetivo posesivo de un adjetivo posesivo?<\/h3>\n<p>Si te gusta la teor\u00eda, la explicaci\u00f3n gramatical es la siguiente:<\/p>\n<p><a href=\"https:\/\/speakingo.com\/es\/adjetivos-ingles\/\">Adjetivos (<em>adjectives<\/em>)<\/a> &#8211; incluidos los posesivos, aparecen antes del sustantivo en la oraci\u00f3n: una <strong>verde<\/strong> casa, <strong>mi<\/strong> casa. P.ej:<\/p>\n<ul>\n<li><em>This is <strong>her<\/strong> boyfriend.<\/em> (Este es su novio).<\/li>\n<li><em>This is <strong>his<\/strong> car.<\/em> (Este es su auto).<\/li>\n<\/ul>\n<p><a href=\"https:\/\/speakingo.com\/es\/pronombres-en-ingles-indefinidos-indefinite-pronouns-someone-somebody-anyone-anybody-noone-nobody-everyone-everybody-one\/\">Los pronombres (<em>pronouns<\/em>)<\/a> a menudo reemplazan a un sustantivo y pueden ser independientes:<\/p>\n<ul>\n<li><em>The cake we ate was <strong>hers<\/strong>.<\/em> (El pastel que comimos era suyo)<\/li>\n<li><em>The money in the bag is <strong>ours<\/strong>. (El dinero de la bolsa es nuestro<\/em>)<\/li>\n<li><em>The phone which is ringing &#8211; I think it&#8217;s <strong>yours<\/strong>.<\/em> (El tel\u00e9fono que suena, probablemente sea el tuyo)<\/li>\n<\/ul>\n<blockquote><p>En resumen, no hay nada despu\u00e9s de los pronombres posesivos, o al menos ning\u00fan sustantivo.<\/p><\/blockquote>\n<p>\u00bfPor qu\u00e9 no un <a href=\"https:\/\/speakingo.com\/es\/singular-plural-ingles\/\">sustantivo<\/a>? Porque hay adjetivos antes de sustantivos. Esta es una situaci\u00f3n poco com\u00fan, pero si eres poeta, puedes comenzar una oraci\u00f3n con un pronombre posesivo y decir algo como:<\/p>\n<ul>\n<li><em>Hers is the snow white horse on the meadow.<\/em> (El suyo es un caballo blanco como la nieve en el prado.)<\/li>\n<\/ul>\n<p><em>\u00abIs\u00bb<\/em> es <a href=\"https:\/\/speakingo.com\/es\/verbos-ingles\/\">un verbo<\/a>, no un sustantivo, as\u00ed que todo est\u00e1 bien. Pero en la calle, no escuchar\u00e1s tal estructura &#8230;<\/p>\n<figure id=\"attachment_5880\" aria-describedby=\"caption-attachment-5880\" style=\"width: 640px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-5880 size-full\" src=\"https:\/\/speakingo.com\/wp-content\/uploads\/2018\/09\/przymiotniki-angielskie-adjectives.jpg\" alt=\"przymiotniki angielskie\" width=\"640\" height=\"397\" \/><figcaption id=\"caption-attachment-5880\" class=\"wp-caption-text\"><em>Lee tambi\u00e9n: <a href=\"https:\/\/speakingo.com\/es\/adjetivos-ingles\/\">C\u00f3mo usar los adjetivos en ingl\u00e9s mejor que Donald Trump y el poeta de la imagen.<\/a><\/em><\/figcaption><\/figure>\n<h2><\/h2>\n<h2><em>My<\/em> o <em>mine<\/em>?<\/h2>\n<p>As\u00ed que si somos la gaviota de \u00abBuscando a Nemo\u00bb, viendo el pez perdido diremos:<\/p>\n<ul>\n<li><em>This is mine.<\/em> \u2013 Esto es m\u00edo. (pronombre posesivo)<\/li>\n<\/ul>\n<p>Pero en esta oraci\u00f3n usaremos <em>my<\/em>:<\/p>\n<ul>\n<li><em>This is my fish.<\/em> \u2013 Ese es mi pez. (adjetivo posesivo)<\/li>\n<\/ul>\n<p><em>Mine<\/em> usamos tambi\u00e9n en la frase <em>a friend of mine:<\/em><\/p>\n<ul>\n<li><em>A friend of mine is getting married next month.<\/em><\/li>\n<\/ul>\n<p>(Un amigo m\u00edo se casar\u00e1 el pr\u00f3ximo mes.)<\/p>\n<h4><em>My<\/em> diremos en las expresiones <em>\u00abmy own\u00bb<\/em> y <em>\u00abon my own\u00bb:<\/em><\/h4>\n<p><em>My own<\/em> &#8211; Mi propio<\/p>\n<ul>\n<li><em>I want to have my own room. <\/em>(Quiero mi propia habitaci\u00f3n)<\/li>\n<\/ul>\n<p><em>On my own<\/em> &#8211; Por mi cuenta<\/p>\n<ul>\n<li><em>I like travelling on my own. <\/em>(Me gusta viajar solo.)<\/li>\n<\/ul>\n<figure id=\"attachment_8463\" aria-describedby=\"caption-attachment-8463\" style=\"width: 640px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8463 size-full\" src=\"https:\/\/speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-pronouns-zaimki-dzierzawcze-dog.jpg\" alt=\"zaimki dzier\u017cawcze, possessive pronouns, dog\" width=\"640\" height=\"480\" \/><figcaption id=\"caption-attachment-8463\" class=\"wp-caption-text\">Es todo m\u00edo, solo necesito orinarlo primero. Lee tambi\u00e9n: <a href=\"https:\/\/speakingo.com\/es\/bulldog-ingles-comandos-para-perro\/\"><em>\u00bfC\u00f3mo hablar con un perro en ingl\u00e9s?\u00a0<\/em><\/a><\/figcaption><\/figure>\n<h2>Ejercicios para pronombres posesivos en ingl\u00e9s <em>(possessive pronouns)<\/em><\/h2>\n<p>Lo m\u00e1s importante es practicar los pronombres posesivos <em>(possessive pronouns). <\/em>No con los ojos en el papel, sino con la garganta, \u00fasalos en una conversaci\u00f3n para acostumbrarte a ellos como una gaviota con su \u00ab\u00a1m\u00edo!\u00bb.<\/p>\n<p>En el <a href=\"https:\/\/speakingo.com\/es\/curso-de-ingles-online\/\" target=\"_blank\" rel=\"noopener noreferrer\">curso de ingl\u00e9s en l\u00ednea de Speakingo<\/a> encontrar\u00e1s toneladas de oraciones con todos estos pronombres (adem\u00e1s de <a href=\"https:\/\/speakingo.com\/es\/pronombres-personales-en-ingles\/\">pronombres personales<\/a>, <a href=\"https:\/\/speakingo.com\/es\/pronombres-reflexivos-reflexive-pronouns\/\">pronombres reflexivos<\/a>, <a href=\"https:\/\/speakingo.com\/es\/relative-clauses-ingles\/\">pronombres relativos<\/a>, <a href=\"https:\/\/speakingo.com\/es\/pronombres-en-ingles-indefinidos-indefinite-pronouns-someone-somebody-anyone-anybody-noone-nobody-everyone-everybody-one\/\">pronombres indefinidos<\/a>, <a href=\"https:\/\/speakingo.com\/es\/there-is-it-is-this-esta-el-ingles\/\">pronombres demostrativos<\/a>, etc.). Lo que en gram\u00e1tica descriptiva nos da dolor de cabeza, durante el curso de ingl\u00e9s online de Speakingo resulta sencillo y obvio, porque aqu\u00ed aprendemos ingl\u00e9s como un ni\u00f1o &#8211; repetimos y hablamos, \u00a1y todo el conocimiento entra en nuestra cabeza sin darnos cuenta!<\/p>\n<p>\u00a1Deber\u00edas probarlo t\u00fa mismo o en tu propia piel! \u00a1La primera semana de prueba es absolutamente gratis!<\/p>\n<hr \/>\n<h3 style=\"text-align: center;\">\u00a1Inscr\u00edbete en el curso de ingl\u00e9s en l\u00ednea de Speakingo!<\/h3>\n<h3 style=\"text-align: center;\"><button type=\"button\" id=\"openLoginModal\"  class=\"btn signup-btn \" href=\"javascript:void(0)\" data-redirect_to=\"\" onclick=\"doAuth(this);\">Comienza a aprender<\/button><\/h3>\n<h4 style=\"text-align: center;\">\u00bfQuieres entender el ingl\u00e9s? \u00a1Empieza a hablar como ellos!<\/h4>\n<hr \/>\n<p><em>\u00bfY cu\u00e1les son tus aventuras con los pronombres posesivos (possessive pronouns)? \u00bfO tal vez tienes algunos memes divertidos con ellos? \u00a1Comparte en los comentarios!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPor qu\u00e9 decimos a veces my y veces mine como la gaviota de Nemo? Porque a veces tenemos que usar el adjetivo posesivo popular y a veces el pronombre posesivo ingl\u00e9s.<\/p>\n","protected":false},"author":1,"featured_media":8462,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3804,3812,3813,3811],"tags":[2732,2733],"class_list":["post-16132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gramatica-inglesa","category-ingles-nivel-avanzado-c1-c2","category-ingles-nivel-intermedio-b1-b2","category-ingles-nivel-principiante-a1-a2","tag-mi-mio-mis-pronombres-posesivos","tag-possessive-pronouns"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.9 (Yoast SEO v22.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns) &#8902; Speakingo<\/title>\n<meta name=\"description\" content=\"\u00bfPor qu\u00e9 decimos a veces que a nosotros ya veces nos gusta la gaviota con la m\u00eda de Nemo? My es un adjetivo posesivo y m\u00edo es un pronombre ingl\u00e9s de inquilino.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns)\" \/>\n<meta property=\"og:description\" content=\"\u00bfPor qu\u00e9 decimos a veces que a nosotros ya veces nos gusta la gaviota con la m\u00eda de Nemo? My es un adjetivo posesivo y m\u00edo es un pronombre ingl\u00e9s de inquilino.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/\" \/>\n<meta property=\"og:site_name\" content=\"Speakingo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/speakingo\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-14T10:07:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-07T14:55:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-pronouns-zaimki-dzierzawcze.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Speakingo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Speakingo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/\"},\"author\":{\"name\":\"Speakingo\",\"@id\":\"https:\/\/www.dev.speakingo.com\/es\/#\/schema\/person\/1a280f36761c452ca0c56a9e657d872a\"},\"headline\":\"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns)\",\"datePublished\":\"2020-09-14T10:07:05+00:00\",\"dateModified\":\"2021-11-07T14:55:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/\"},\"wordCount\":923,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.dev.speakingo.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-pronouns-zaimki-dzierzawcze.gif\",\"keywords\":[\"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos\",\"possessive pronouns\"],\"articleSection\":[\"Gram\u00e1tica inglesa\",\"Nivel avanzado (C1-C2)\",\"Nivel intermedio (B1-B2)\",\"Nivel principiante (A1-A2)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/\",\"url\":\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/\",\"name\":\"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns) &#8902; Speakingo\",\"isPartOf\":{\"@id\":\"https:\/\/www.dev.speakingo.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-pronouns-zaimki-dzierzawcze.gif\",\"datePublished\":\"2020-09-14T10:07:05+00:00\",\"dateModified\":\"2021-11-07T14:55:13+00:00\",\"description\":\"\u00bfPor qu\u00e9 decimos a veces que a nosotros ya veces nos gusta la gaviota con la m\u00eda de Nemo? My es un adjetivo posesivo y m\u00edo es un pronombre ingl\u00e9s de inquilino.\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#primaryimage\",\"url\":\"https:\/\/dev.speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-pronouns-zaimki-dzierzawcze.gif\",\"contentUrl\":\"https:\/\/dev.speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-pronouns-zaimki-dzierzawcze.gif\",\"width\":640,\"height\":480,\"caption\":\"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Speakingo\",\"item\":\"https:\/\/dev.speakingo.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gram\u00e1tica inglesa\",\"item\":\"https:\/\/dev.speakingo.com\/es\/category\/gramatica-inglesa\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dev.speakingo.com\/es\/#website\",\"url\":\"https:\/\/www.dev.speakingo.com\/es\/\",\"name\":\"Speakingo\",\"description\":\"Learn English Online!\",\"publisher\":{\"@id\":\"https:\/\/www.dev.speakingo.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dev.speakingo.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dev.speakingo.com\/es\/#organization\",\"name\":\"Speakingo\",\"url\":\"https:\/\/www.dev.speakingo.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.dev.speakingo.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/speakingo.com\/wp-content\/uploads\/2021\/04\/speakingo-kurs-jezyka-angielskiego-online-curso-ingles-sukces-main-english.png.jpg\",\"contentUrl\":\"https:\/\/speakingo.com\/wp-content\/uploads\/2021\/04\/speakingo-kurs-jezyka-angielskiego-online-curso-ingles-sukces-main-english.png.jpg\",\"width\":500,\"height\":344,\"caption\":\"Speakingo\"},\"image\":{\"@id\":\"https:\/\/www.dev.speakingo.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/speakingo\/\",\"https:\/\/www.youtube.com\/channel\/UC5u_DFTWwYDEI1GGjo5lFnQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dev.speakingo.com\/es\/#\/schema\/person\/1a280f36761c452ca0c56a9e657d872a\",\"name\":\"Speakingo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.dev.speakingo.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5018e96a28455ead2207f12d70ffc10289e8640d48019b6c4e66517dc3a37a01?s=96&d=monsterid&r=pg\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5018e96a28455ead2207f12d70ffc10289e8640d48019b6c4e66517dc3a37a01?s=96&d=monsterid&r=pg\",\"caption\":\"Speakingo\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns) &#8902; Speakingo","description":"\u00bfPor qu\u00e9 decimos a veces que a nosotros ya veces nos gusta la gaviota con la m\u00eda de Nemo? My es un adjetivo posesivo y m\u00edo es un pronombre ingl\u00e9s de inquilino.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns)","og_description":"\u00bfPor qu\u00e9 decimos a veces que a nosotros ya veces nos gusta la gaviota con la m\u00eda de Nemo? My es un adjetivo posesivo y m\u00edo es un pronombre ingl\u00e9s de inquilino.","og_url":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/","og_site_name":"Speakingo","article_publisher":"https:\/\/www.facebook.com\/speakingo\/","article_published_time":"2020-09-14T10:07:05+00:00","article_modified_time":"2021-11-07T14:55:13+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/dev.speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-pronouns-zaimki-dzierzawcze.gif","type":"image\/gif"}],"author":"Speakingo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Speakingo","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#article","isPartOf":{"@id":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/"},"author":{"name":"Speakingo","@id":"https:\/\/www.dev.speakingo.com\/es\/#\/schema\/person\/1a280f36761c452ca0c56a9e657d872a"},"headline":"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns)","datePublished":"2020-09-14T10:07:05+00:00","dateModified":"2021-11-07T14:55:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/"},"wordCount":923,"commentCount":0,"publisher":{"@id":"https:\/\/www.dev.speakingo.com\/es\/#organization"},"image":{"@id":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-pronouns-zaimki-dzierzawcze.gif","keywords":["\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos","possessive pronouns"],"articleSection":["Gram\u00e1tica inglesa","Nivel avanzado (C1-C2)","Nivel intermedio (B1-B2)","Nivel principiante (A1-A2)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/","url":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/","name":"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns) &#8902; Speakingo","isPartOf":{"@id":"https:\/\/www.dev.speakingo.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#primaryimage"},"image":{"@id":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-pronouns-zaimki-dzierzawcze.gif","datePublished":"2020-09-14T10:07:05+00:00","dateModified":"2021-11-07T14:55:13+00:00","description":"\u00bfPor qu\u00e9 decimos a veces que a nosotros ya veces nos gusta la gaviota con la m\u00eda de Nemo? My es un adjetivo posesivo y m\u00edo es un pronombre ingl\u00e9s de inquilino.","breadcrumb":{"@id":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#primaryimage","url":"https:\/\/dev.speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-pronouns-zaimki-dzierzawcze.gif","contentUrl":"https:\/\/dev.speakingo.com\/wp-content\/uploads\/2019\/03\/possessive-pronouns-zaimki-dzierzawcze.gif","width":640,"height":480,"caption":"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns)"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.speakingo.com\/es\/pronombres-posesivos-possessive-pronouns\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Speakingo","item":"https:\/\/dev.speakingo.com\/es\/"},{"@type":"ListItem","position":2,"name":"Gram\u00e1tica inglesa","item":"https:\/\/dev.speakingo.com\/es\/category\/gramatica-inglesa\/"},{"@type":"ListItem","position":3,"name":"\u00a1Mi! \u00a1M\u00edo! \u00a1Mis pronombres posesivos! (possessive pronouns)"}]},{"@type":"WebSite","@id":"https:\/\/www.dev.speakingo.com\/es\/#website","url":"https:\/\/www.dev.speakingo.com\/es\/","name":"Speakingo","description":"Learn English Online!","publisher":{"@id":"https:\/\/www.dev.speakingo.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dev.speakingo.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.dev.speakingo.com\/es\/#organization","name":"Speakingo","url":"https:\/\/www.dev.speakingo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.dev.speakingo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/speakingo.com\/wp-content\/uploads\/2021\/04\/speakingo-kurs-jezyka-angielskiego-online-curso-ingles-sukces-main-english.png.jpg","contentUrl":"https:\/\/speakingo.com\/wp-content\/uploads\/2021\/04\/speakingo-kurs-jezyka-angielskiego-online-curso-ingles-sukces-main-english.png.jpg","width":500,"height":344,"caption":"Speakingo"},"image":{"@id":"https:\/\/www.dev.speakingo.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/speakingo\/","https:\/\/www.youtube.com\/channel\/UC5u_DFTWwYDEI1GGjo5lFnQ"]},{"@type":"Person","@id":"https:\/\/www.dev.speakingo.com\/es\/#\/schema\/person\/1a280f36761c452ca0c56a9e657d872a","name":"Speakingo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.dev.speakingo.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5018e96a28455ead2207f12d70ffc10289e8640d48019b6c4e66517dc3a37a01?s=96&d=monsterid&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5018e96a28455ead2207f12d70ffc10289e8640d48019b6c4e66517dc3a37a01?s=96&d=monsterid&r=pg","caption":"Speakingo"}}]}},"_links":{"self":[{"href":"https:\/\/dev.speakingo.com\/es\/wp-json\/wp\/v2\/posts\/16132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.speakingo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.speakingo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.speakingo.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.speakingo.com\/es\/wp-json\/wp\/v2\/comments?post=16132"}],"version-history":[{"count":0,"href":"https:\/\/dev.speakingo.com\/es\/wp-json\/wp\/v2\/posts\/16132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.speakingo.com\/es\/wp-json\/wp\/v2\/media\/8462"}],"wp:attachment":[{"href":"https:\/\/dev.speakingo.com\/es\/wp-json\/wp\/v2\/media?parent=16132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.speakingo.com\/es\/wp-json\/wp\/v2\/categories?post=16132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.speakingo.com\/es\/wp-json\/wp\/v2\/tags?post=16132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}